{"id":816,"date":"2010-04-09T00:56:16","date_gmt":"2010-04-09T00:56:16","guid":{"rendered":"http:\/\/www.pianomundo.com.ar\/rockpop\/?p=816"},"modified":"2010-04-09T00:56:16","modified_gmt":"2010-04-09T00:56:16","slug":"%c2%a1como-crear-sus-propias-composiciones-de-piano-rapida-y-facilmente","status":"publish","type":"post","link":"https:\/\/www.pianomundo.com.ar\/rockpop\/%c2%a1como-crear-sus-propias-composiciones-de-piano-rapida-y-facilmente\/","title":{"rendered":"\u00a1C\u00f3mo crear sus propias composiciones de piano r\u00e1pida y f\u00e1cilmente!"},"content":{"rendered":"<p>A continuaci\u00f3n le presento uno de mis m\u00e9todos favoritos para r\u00e1pidamente terminar secciones enteras de  m\u00fasica y <a href=\"http:\/\/www.pianomundo.com.ar\/teoria\/componer.html\">crear una composici\u00f3n<\/a> completa para piano. Primero tendr\u00e1 que dibujar 8-barras en un pedazo de papel. Yo uso 8-barras primero porque es un espacio relativamente peque\u00f1o para \u00abllenar\u00bb r\u00e1pidamente. Usted no tiene que utilizar hojas pentagramadas. Cualquier papel servir\u00e1. De hecho, yo uso un cuaderno con espiral con p\u00e1ginas en blanco. Escribo 8-barras y voila, he anotado lo que se convertir\u00e1 en una secci\u00f3n de m\u00fasica.<br \/>\n<center><a href=\"http:\/\/www.pianomundo.com.ar\/rockpop\/wp-content\/uploads\/2009\/11\/11767423561.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.pianomundo.com.ar\/rockpop\/wp-content\/uploads\/2009\/11\/11767423561-300x300.jpg\" alt=\"\" title=\"Componer en el piano\" width=\"300\" height=\"300\" class=\"alignnone size-medium wp-image-695\" srcset=\"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-content\/uploads\/2009\/11\/11767423561-300x300.jpg 300w, https:\/\/www.pianomundo.com.ar\/rockpop\/wp-content\/uploads\/2009\/11\/11767423561-150x150.jpg 150w, https:\/\/www.pianomundo.com.ar\/rockpop\/wp-content\/uploads\/2009\/11\/11767423561.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><center><br \/>\nAhora viene la parte interesante. La mayor\u00eda de <a href=\"http:\/\/www.pianomundo.com.ar\/operas\/\">los compositores<\/a> comienzan primero con la l\u00ednea de melod\u00eda. No hay nada malo en esto. Pero si realmente quiere terminar una secci\u00f3n r\u00e1pidamente, comience con los cambios de acordes. \u00bfPor qu\u00e9? Debido a que podr\u00e1 bloquear las barras de la musica mucho m\u00e1s r\u00e1pido. Esto es lo que quiero decir. <\/p>\n<p>Digamos que quiere crear algo en la escala de Fa Mayor. Genial. Ahora sabemos que tenemos por lo menos 6 acordes con los cual se puede trabajar. Mediante el uso de s\u00f3lo 3 acordes, podemos bloquear a nuestras 8-barras. \u00bfC\u00f3mo? Mire&#8230; Digamos que tenemos el acorde de Fa Mayor 7 para las primeras 4 barras, luego viene Si bemol mayor para 2 barras y Do 7 para las \u00faltimas 2 barras. Hemos creado as\u00ed <a href=\"http:\/\/www.pianomundo.com.ar\/rockpop\/aprendiendo-a-crear-amonias-con-los-acordes\/\">una progresi\u00f3n de acordes<\/a>. Usted puede hacer esto en menos de un minuto. \u00a1Lo juro! Es as\u00ed de f\u00e1cil. Ahora todo lo que tiene que hacer es decidir el tipo de arreglo que crear\u00e1 para estos acordes. <\/p>\n<p>Pueden ser arpegios, acordes cerrados, acordes abiertos&#8230; lo que sea. El punto aqu\u00ed es que, utilizando acordes, se puede trazar un territorio arm\u00f3nico. Ahora usted puede <a href=\"http:\/\/www.pianomundo.com.ar\/rockpop\/como-crear-sus-propias-composiciones-de-piano\/\">crear una melod\u00eda<\/a> con estos acordes, o mantenerlo totalmente texturado. \u00a1Depende de usted! \u00a1Int\u00e9ntelo!. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A continuaci\u00f3n le presento uno de mis m\u00e9todos favoritos para r\u00e1pidamente terminar secciones enteras de m\u00fasica y crear una composici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":738,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[7],"tags":[],"class_list":["post-816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pianos"],"_links":{"self":[{"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/posts\/816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/comments?post=816"}],"version-history":[{"count":3,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/posts\/816\/revisions"}],"predecessor-version":[{"id":839,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/posts\/816\/revisions\/839"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/media\/738"}],"wp:attachment":[{"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/media?parent=816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/categories?post=816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.pianomundo.com.ar\/rockpop\/wp-json\/wp\/v2\/tags?post=816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}